{"id":16961,"date":"2026-09-01T14:54:29","date_gmt":"2026-09-01T17:54:29","guid":{"rendered":"https:\/\/www.jpasini.com.br\/site\/cmn-amplia-limite-de-credito-para-operacoes-do-novo-pac-em-2026\/"},"modified":"2026-09-01T14:54:29","modified_gmt":"2026-09-01T17:54:29","slug":"cmn-amplia-limite-de-credito-para-operacoes-do-novo-pac-em-2026","status":"publish","type":"post","link":"https:\/\/www.jpasini.com.br\/site\/cmn-amplia-limite-de-credito-para-operacoes-do-novo-pac-em-2026\/","title":{"rendered":"CMN amplia limite de cr\u00e9dito para opera\u00e7\u00f5es do Novo PAC em 2026"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cbic.org.br\/wp-content\/uploads\/2022\/09\/realmoedadinheirojfcrzabr17012200451.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/><\/p>\n<p>O Conselho Monet\u00e1rio Nacional (CMN) publicou, no Di\u00e1rio Oficial da Uni\u00e3o (DOU), a Resolu\u00e7\u00e3o CMN n\u00ba 5.339, de 27 de agosto de 2026, que amplia os limites destinados \u00e0s opera\u00e7\u00f5es de cr\u00e9dito do Novo Programa de Acelera\u00e7\u00e3o do Crescimento (Novo PAC) em 2026.<\/p>\n<p><strong>Novo PAC<\/strong><\/p>\n<p>Nas opera\u00e7\u00f5es sem garantia da Uni\u00e3o, o sublimite destinado ao Novo PAC passou de R$ 1,2 bilh\u00e3o para R$ 2,2 bilh\u00f5es, representando acr\u00e9scimo de R$ 1 bilh\u00e3o.<\/p>\n<p>J\u00e1 nas opera\u00e7\u00f5es com garantia da Uni\u00e3o, o limite passou de R$ 1,8 bilh\u00e3o para R$ 2,8 bilh\u00f5es. Nesse caso, a amplia\u00e7\u00e3o decorre do remanejamento do sublimite espec\u00edfico de R$ 1 bilh\u00e3o anteriormente destinado \u00e0s Parcerias P\u00fablico-Privadas (PPPs), que foi extinto e transferido integralmente para as opera\u00e7\u00f5es do Novo PAC.<\/p>\n<p><strong>Estados e munic\u00edpios<\/strong><\/p>\n<p>A medida tamb\u00e9m amplia os limites para contrata\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9dito por estados, Distrito Federal e munic\u00edpios em 2026. Com a medida, o limite anual destinado aos \u00f3rg\u00e3os e entidades dos entes subnacionais passou de R$ 23,625 bilh\u00f5es para R$ 26,625 bilh\u00f5es, acr\u00e9scimo de R$ 3 bilh\u00f5es.<\/p>\n<p>Nas opera\u00e7\u00f5es com garantia da Uni\u00e3o, o limite foi ampliado de R$ 5,5 bilh\u00f5es para R$ 7 bilh\u00f5es, representando aumento de R$ 1,5 bilh\u00e3o. Para as opera\u00e7\u00f5es sem garantia da Uni\u00e3o, o teto passou de R$ 5,5 bilh\u00f5es para R$ 6 bilh\u00f5es, com acr\u00e9scimo de R$ 500 milh\u00f5es.<\/p>\n<p>N\u00e3o houve altera\u00e7\u00e3o nos sublimites destinados \u00e0 Empresa Brasileira de Correios e Tel\u00e9grafos (Correios), mantido em R$ 8 bilh\u00f5es, nem aos \u00f3rg\u00e3os e entidades da Uni\u00e3o, que permanecem com limite de R$ 625 milh\u00f5es.<\/p>\n<p><strong>Contexto<\/strong><\/p>\n<p>Segundo o Minist\u00e9rio da Fazenda, a amplia\u00e7\u00e3o do espa\u00e7o para contrata\u00e7\u00e3o de cr\u00e9dito pelos entes subnacionais foi viabilizada a partir de recursos que n\u00e3o dever\u00e3o ser utilizados at\u00e9 o final de 2026 no \u00e2mbito do Programa de Reestrutura\u00e7\u00e3o e de Ajuste Fiscal (PAF) e do Programa de Acompanhamento e Transpar\u00eancia Fiscal (PATF).<\/p>\n<p>A Secretaria do Tesouro Nacional (STN) identificou essa margem a partir de levantamento realizado com os entes participantes dos programas. Parte do espa\u00e7o dispon\u00edvel foi ent\u00e3o realocada para os sublimites de cr\u00e9dito subnacional definidos pelo CMN, que, segundo o Minist\u00e9rio da Fazenda, estavam com saldo dispon\u00edvel pr\u00f3ximo do esgotamento.<\/p>\n<p>The post <a href=\"https:\/\/cbic.org.br\/cmn-amplia-limite-de-credito-para-operacoes-do-novo-pac-em-2026\/\">CMN amplia limite de cr\u00e9dito para opera\u00e7\u00f5es do Novo PAC em 2026<\/a> appeared first on <a href=\"https:\/\/cbic.org.br\/\">CBIC \u2013 C\u00e2mara Brasileira da Industria da Constru\u00e7\u00e3o<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Conselho Monet\u00e1rio Nacional (CMN) publicou, no Di\u00e1rio Oficial da Uni\u00e3o (DOU), a Resolu\u00e7\u00e3o CMN n\u00ba 5.339, de 27 de agosto de 2026, que amplia os limites destinados \u00e0s opera\u00e7\u00f5es de cr\u00e9dito do Novo Programa de Acelera\u00e7\u00e3o do Crescimento (Novo PAC) em 2026. Novo PAC&#8230;<\/p>\n","protected":false},"author":2,"featured_media":16962,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[],"class_list":["post-16961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-imobiliario"],"_links":{"self":[{"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/posts\/16961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/comments?post=16961"}],"version-history":[{"count":0,"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/posts\/16961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/media\/16962"}],"wp:attachment":[{"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/media?parent=16961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/categories?post=16961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpasini.com.br\/site\/wp-json\/wp\/v2\/tags?post=16961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}